{"id":3469,"date":"2023-12-03T18:38:03","date_gmt":"2023-12-03T17:38:03","guid":{"rendered":"https:\/\/gissacg.fr\/?p=3469"},"modified":"2024-03-22T18:22:14","modified_gmt":"2024-03-22T17:22:14","slug":"notre-ag-du-2-decembre-2023","status":"publish","type":"post","link":"https:\/\/gissacg.fr\/index.php\/2023\/12\/03\/notre-ag-du-2-decembre-2023\/","title":{"rendered":"Notre AG du 2 d\u00e9cembre 2023"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-1024x768.jpg\" alt=\"\" class=\"wp-image-3463 size-full\" srcset=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-1024x768.jpg 1024w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-300x225.jpg 300w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-768x576.jpg 768w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-1536x1152.jpg 1536w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-2048x1536.jpg 2048w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-150x113.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Une vingtaine de membres ont particip\u00e9 \u00e0 l&rsquo;AG au CNPG pour voter le rapport moral de notre pr\u00e9sident et le rapport financier de notre tr\u00e9sorier. Les responsables de commission ont pr\u00e9sent\u00e9 les activit\u00e9s de l&rsquo;ann\u00e9e et les perspectives pour la prochaine saison.  Nous avons eu aussi la pr\u00e9sence et des interventions de Patrick Loisel, adjoint au nautisme \u00e0 la ville de Perros-Guirec ainsi que du pr\u00e9sident du Codep22, Nicolas M\u00e9rad.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p><\/p>\n\n\n\n<p>De plus, le pr\u00e9sident de l&rsquo;ASN, Alexandre Gusse, est venu nous remercier pour le pr\u00eat du Tritonia lors de la Coupe Internationale d\u2019\u00c9t\u00e9 d&rsquo;Optimist. Puis le vote de renouvellement du CA. Enfin, un POT convivial avec la traditionnelle auberge espagnole pour celles et ceux qui pouvaient rester. Merci pour les d\u00e9lices apport\u00e9s.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-1024x707.jpg\" alt=\"\" class=\"wp-image-3465 size-full\" srcset=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-1024x707.jpg 1024w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-300x207.jpg 300w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-768x530.jpg 768w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-1536x1060.jpg 1536w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-2048x1414.jpg 2048w, https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_173801-rog-comp-150x104.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-advgb-images-slider advgb-images-slider-block advg-images-slider-b4a9e87c-8320-4c9b-a50f-4509977c7260\"><div class=\"advgb-images-slider\" dir=\"ltr\"><div class=\"advgb-image-slider-item\"><img decoding=\"async\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_172749-comp-scaled.jpg\" class=\"advgb-image-slider-img\" alt=\"remerciements par l'ASN et la Ville de Perros\" style=\"width:100%;height:auto\"\/><div class=\"advgb-image-slider-item-info\" style=\"justify-content:center;align-items:center\"><h4 class=\"advgb-image-slider-title\"><span class=\"ez-toc-section\" id=\"remerciements_par_lASN_et_la_Ville_de_Perros\"><\/span>remerciements par l&rsquo;ASN et la Ville de Perros<span class=\"ez-toc-section-end\"><\/span><\/h4><\/div><\/div><div class=\"advgb-image-slider-item\"><img decoding=\"async\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/Capture-CIE-optimis-15-au-21-juil-23-et-bateau-gissacg.png\" class=\"advgb-image-slider-img\" alt=\"CIE optimist 15 au 21 juil 23 et bateau gissacg\" style=\"width:100%;height:auto\"\/><div class=\"advgb-image-slider-item-info\" style=\"justify-content:center;align-items:center\"><h4 class=\"advgb-image-slider-title\"><span class=\"ez-toc-section\" id=\"CIE_optimist_15_au_21_juil_23_et_bateau_gissacg\"><\/span>CIE optimist 15 au 21 juil 23 et bateau gissacg<span class=\"ez-toc-section-end\"><\/span><\/h4><\/div><\/div><div class=\"advgb-image-slider-item\"><img decoding=\"async\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_201132-rog-comp-scaled.jpg\" class=\"advgb-image-slider-img\" alt=\"amuse-gueules\" style=\"width:100%;height:auto\"\/><div class=\"advgb-image-slider-item-info\" style=\"justify-content:center;align-items:center\"><h4 class=\"advgb-image-slider-title\"><span class=\"ez-toc-section\" id=\"amuse-gueules\"><\/span>amuse-gueules<span class=\"ez-toc-section-end\"><\/span><\/h4><\/div><\/div><div class=\"advgb-image-slider-item\"><img decoding=\"async\" src=\"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_201141-rog-comp-scaled.jpg\" class=\"advgb-image-slider-img\" alt=\"sucr\u00e9-sal\u00e9 pour tous les go\u00fbts\" style=\"width:100%;height:auto\"\/><div class=\"advgb-image-slider-item-info\" style=\"justify-content:center;align-items:center\"><h4 class=\"advgb-image-slider-title\"><span class=\"ez-toc-section\" id=\"sucre-sale_pour_tous_les_gouts\"><\/span>sucr\u00e9-sal\u00e9 pour tous les go\u00fbts<span class=\"ez-toc-section-end\"><\/span><\/h4><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une vingtaine de membres ont particip\u00e9 \u00e0 l&rsquo;AG au CNPG pour voter le rapport moral de notre pr\u00e9sident et le rapport financier de notre tr\u00e9sorier. Les responsables de commission ont pr\u00e9sent\u00e9 les activit\u00e9s de l&rsquo;ann\u00e9e et les perspectives pour la prochaine saison. Nous avons eu aussi la pr\u00e9sence et des&#8230;<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/gissacg.fr\/index.php\/2023\/12\/03\/notre-ag-du-2-decembre-2023\/\">Lire la suite<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":8,"featured_media":3463,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpm_timeformat":"","_wpm_styles":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[111,118,117,124],"tags":[8],"class_list":["post-3469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saison-2022-2023","category-saison-2023-2024","category-vie-du-club-2022-2023","category-vie-du-club-2023-2024","tag-ag"],"author_meta":{"display_name":"Isabelle Pettier","author_link":"https:\/\/gissacg.fr\/index.php\/author\/ipettier\/"},"featured_img":"https:\/\/gissacg.fr\/wp-content\/uploads\/2023\/12\/20231202_170707-comp-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/gissacg.fr\/index.php\/category\/zarchive\/saison-2022-2023\/\" class=\"advgb-post-tax-term\">Saison 2022-2023<\/a>","<a href=\"https:\/\/gissacg.fr\/index.php\/category\/zarchive\/saison-2023-2024\/\" class=\"advgb-post-tax-term\">Saison 2023-2024<\/a>","<a href=\"https:\/\/gissacg.fr\/index.php\/category\/zarchive\/saison-2022-2023\/vie-du-club-2022-2023\/\" class=\"advgb-post-tax-term\">Vie du club 2022-2023<\/a>","<a href=\"https:\/\/gissacg.fr\/index.php\/category\/zarchive\/saison-2023-2024\/vie-du-club-2023-2024\/\" class=\"advgb-post-tax-term\">Vie du club 2023-2024<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Saison 2022-2023<\/span>","<span class=\"advgb-post-tax-term\">Saison 2023-2024<\/span>","<span class=\"advgb-post-tax-term\">Vie du club 2022-2023<\/span>","<span class=\"advgb-post-tax-term\">Vie du club 2023-2024<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/gissacg.fr\/index.php\/category\/zarchive\/saison-2023-2024\/vie-du-club-2023-2024\/\" class=\"advgb-post-tax-term\">AG<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">AG<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 2 ans il y a","modified":"Mis \u00e0 jour 2 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 3 d\u00e9cembre 2023","modified":"Mise \u00e0 jour le 22 mars 2024"},"absolute_dates_time":{"created":"Publi\u00e9 le 3 d\u00e9cembre 2023 18 h 38 min","modified":"Mise \u00e0 jour le 22 mars 2024 18 h 22 min"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/posts\/3469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3469"}],"version-history":[{"count":9,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/posts\/3469\/revisions"}],"predecessor-version":[{"id":3882,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/posts\/3469\/revisions\/3882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/media\/3463"}],"wp:attachment":[{"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gissacg.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}